{"id":1762,"date":"2022-02-02T08:37:28","date_gmt":"2022-02-02T07:37:28","guid":{"rendered":"http:\/\/s898510583.online.de\/hotels\/hotel-hedera-a-rabac\/"},"modified":"2025-05-23T10:12:40","modified_gmt":"2025-05-23T09:12:40","slug":"hotel-hedera-a-rabac","status":"publish","type":"hotels","link":"https:\/\/alpotels.com\/it\/hotels\/hotel-hedera-a-rabac\/","title":{"rendered":"Hotel Hedera a Rabac"},"content":{"rendered":"\n<p>L&#8217;Hotel Hedera con la sua atmosfera accogliente si trova a soli 50 m dalla spiaggia ed \u00e8 il punto di partenza perfetto per una vacanza rilassante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Hotel Hedera con la sua atmosfera accogliente si trova a soli 50 m dalla spiaggia ed \u00e8 il punto di partenza perfetto per una vacanza rilassante.<\/p>\n","protected":false},"featured_media":1608,"template":"","categories":[22],"tags":[],"class_list":["post-1762","hotels","type-hotels","status-publish","has-post-thumbnail","hentry","category-istria"],"acf":[],"_links":{"self":[{"href":"https:\/\/alpotels.com\/it\/wp-json\/wp\/v2\/hotels\/1762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpotels.com\/it\/wp-json\/wp\/v2\/hotels"}],"about":[{"href":"https:\/\/alpotels.com\/it\/wp-json\/wp\/v2\/types\/hotels"}],"version-history":[{"count":5,"href":"https:\/\/alpotels.com\/it\/wp-json\/wp\/v2\/hotels\/1762\/revisions"}],"predecessor-version":[{"id":2331,"href":"https:\/\/alpotels.com\/it\/wp-json\/wp\/v2\/hotels\/1762\/revisions\/2331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alpotels.com\/it\/wp-json\/wp\/v2\/media\/1608"}],"wp:attachment":[{"href":"https:\/\/alpotels.com\/it\/wp-json\/wp\/v2\/media?parent=1762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alpotels.com\/it\/wp-json\/wp\/v2\/categories?post=1762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alpotels.com\/it\/wp-json\/wp\/v2\/tags?post=1762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}